{"id":1322,"date":"2025-01-08T15:31:57","date_gmt":"2025-01-08T15:31:57","guid":{"rendered":"https:\/\/cbwebsite-d8grhmhsf4dfb0cz.germanywestcentral-01.azurewebsites.net\/home\/"},"modified":"2025-10-07T10:22:23","modified_gmt":"2025-10-07T10:22:23","slug":"home","status":"publish","type":"page","link":"https:\/\/www.cyberbasics.org\/en\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-494c42c4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9fed0b66\"><h1 class=\"uagb-heading-text\"><strong>The smart compliance platform<\/strong><\/h1><p class=\"uagb-desc-text\">For NIS2, ISO9001, ISO27001:2022, NEN7510:2024, AVG\/GDPR, LGPD and more.<\/p><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-cc9d0965 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.67%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-uagb-container uagb-block-2eac84a9\">\n<div class=\"wp-block-uagb-info-box uagb-block-e78c5b8d uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\"><strong>Quick action?<\/strong><\/h3><\/div><\/div><p class=\"uagb-ifb-desc\">Would you like to follow up on our contact, or plan a demo of Cyber Basics?<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-a3927b5d wp-block-buttons-is-layout-flex\" style=\"padding-top:0;padding-right:var(--wp--preset--spacing--30);padding-bottom:0;padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-align-left wp-element-button\" href=\"\/en\/contact\/\">Click here<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bd487c2d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-61309fdb\"><h2 class=\"uagb-heading-text\">We made it efficient and convenient<\/h2><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-border-color has-white-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-006c6494 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Structured approach<\/h3><\/div><p class=\"uagb-ifb-desc\">With our cybersecurity compliance platform, you get a structured approach to continuously comply with laws and regulations.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-ast-global-color-5-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-9a95a3a8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Policies\/procedures<\/h3><\/div><p class=\"uagb-ifb-desc\">All portals are equipped with standard policies and procedures. This will get you on the right track. And of course, there is plenty of room to add your additional policies\/procedures.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-ast-global-color-5-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-0358dc83 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Requirements overview<\/h3><\/div><p class=\"uagb-ifb-desc\">All requirements are clearly worked out in the portals by our team of legal\/technical experts. This provides overview and structure.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-border-color has-ast-global-color-5-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-ee927032 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Technical requirements<\/h3><\/div><p class=\"uagb-ifb-desc\">We have cleverly incorporated legal and technical requirements into the various portals. Collaborate smartly with your IT vendors and partners.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-ast-global-color-5-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-3b71a969 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">DIY or guided<\/h3><\/div><p class=\"uagb-ifb-desc\">Cyber Basics has been developed to be able to implement and maintain legislation\/standards independently as much as possible. If desired, we can also guide you.<\/p><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-border-color has-ast-global-color-5-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"border-color:#d1dae67a;border-width:1px;border-radius:18px\">\n<div class=\"wp-block-uagb-info-box uagb-block-25814703 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256zM371.8 211.8C382.7 200.9 382.7 183.1 371.8 172.2C360.9 161.3 343.1 161.3 332.2 172.2L224 280.4L179.8 236.2C168.9 225.3 151.1 225.3 140.2 236.2C129.3 247.1 129.3 264.9 140.2 275.8L204.2 339.8C215.1 350.7 232.9 350.7 243.8 339.8L371.8 211.8z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">SaaS-platform<\/h3><\/div><p class=\"uagb-ifb-desc\">Cyber Basics offers the cybersecurity compliance platform as a secure SaaS solution, so you can get started right away.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-71c3852e\"><h2 class=\"uagb-heading-text\">Your cybersecurity compliance platform in one overview<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-587003d3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-de867c4d\">\n<div class=\"wp-block-uagb-counter uagb-block-447ba5b4 wp-block-uagb-counter--number\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"1000\" data-from-value=\"0\" data-delimiter=\".\"><\/span><span class=\"uagb-counter-block-suffix\">+<\/span><\/div><div class=\"wp-block-uagb-counter__title\">Cyber Basics users<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a95a4438\">\n<div class=\"wp-block-uagb-counter uagb-block-57a687ba wp-block-uagb-counter--number\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"15\" data-from-value=\"0\" data-delimiter=\",\"><\/span><\/div><div class=\"wp-block-uagb-counter__title\">Compliance portals<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7f2408d3\">\n<div class=\"wp-block-uagb-counter uagb-block-595d0164 wp-block-uagb-counter--number\"><div class=\"wp-block-uagb-counter__number\"><span class=\"uagb-counter-block-prefix\">in <\/span><span class=\"uagb-counter-block-number\" data-duration=\"1.5\" data-to-value=\"3\" data-from-value=\"0\" data-delimiter=\",\"><\/span><\/div><div class=\"wp-block-uagb-counter__title\">Steps to compliance<\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3cd30340 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-1ddfafc8 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp ,https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp 780w, https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp\" alt=\"Cyber Basics cybersecurity compliance platform logo\" class=\"uag-image-3207 lazyload\" width=\"400\" height=\"400\" title=\"Cyber-Basics-logoblock\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/400;\" \/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-medium-font-size is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1e9040bf\"><h2 class=\"uagb-heading-text\">1 modular SaaS platform<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-4bf80251\"><h2 class=\"uagb-heading-text\">Multiple ISMS-portals<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-5262aa25\"><h2 class=\"uagb-heading-text\">Working together smartly<\/h2><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5fcee4f8 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2b5f3149\"><h2 class=\"uagb-heading-text\">The portals<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4a8e1942\">\n\n\n<div class=\"wp-block-uagb-container uagb-block-86432e93\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-fb56e858 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png ,\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png 780w, \/wp-content\/uploads\/2025\/03\/NIS2-ENG.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png\" alt=\"NIS2 Cyber Basics box\" class=\"uag-image-3089 lazyload\" width=\"500\" height=\"500\" title=\"NIS2 ENG\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f1094065\"><h3 class=\"uagb-heading-text\"><strong>NIS2 Directive<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">The European NIS2 directive incorporated into a comprehensive portal.<\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#NIS2-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-01df3a06\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-a2ec8e61 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/10\/ISO9001.png ,https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/10\/ISO9001.png 780w, https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/10\/ISO9001.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/10\/ISO9001.png\" alt=\"\" class=\"uag-image-3727 lazyload\" width=\"500\" height=\"500\" title=\"ISO9001\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b17f6847\"><h3 class=\"uagb-heading-text\"><strong>ISO9001:2015<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">The ISO9001:2015 portal, ready for smart and efficient use. <\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#ISO9001-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c988f562\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-a35d235b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/03\/ISO270012022.png ,\/wp-content\/uploads\/2025\/03\/ISO270012022.png 780w, \/wp-content\/uploads\/2025\/03\/ISO270012022.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/03\/ISO270012022.png\" alt=\"ISO27001:2022\" class=\"uag-image-2991 lazyload\" width=\"500\" height=\"500\" title=\"ISO270012022\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b07219d5\"><h3 class=\"uagb-heading-text\"><strong>ISO27001:2022<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">Use our ISO27001:2022 portal, as well as more than 1000 other users. <\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#ISO27001-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-efea18e5\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-8a765627 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/03\/NEN7510.png ,\/wp-content\/uploads\/2025\/03\/NEN7510.png 780w, \/wp-content\/uploads\/2025\/03\/NEN7510.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/03\/NEN7510.png\" alt=\"NEN7510\" class=\"uag-image-2989 lazyload\" width=\"500\" height=\"500\" title=\"NEN7510\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-70c2c644\"><h3 class=\"uagb-heading-text\"><strong>NEN7510:2024<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">The revised NEN7510:2024 is now available directly from us.<\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#NEN7510-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a890f82a\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-c175cf2f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png ,\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png 780w, \/wp-content\/uploads\/2025\/03\/NIS2-ENG.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/03\/NIS2-ENG.png\" alt=\"NIS2 Cyber Basics box\" class=\"uag-image-3089 lazyload\" width=\"500\" height=\"500\" title=\"NIS2 ENG\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-79357460\"><h3 class=\"uagb-heading-text\"><strong>NIS2 supply chain<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">Specially developed for the chain partner\/supplier.<\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#NIS2-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9d8fb7eb\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-c3cf6ea0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/03\/AVGGDPR.png ,\/wp-content\/uploads\/2025\/03\/AVGGDPR.png 780w, \/wp-content\/uploads\/2025\/03\/AVGGDPR.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/03\/AVGGDPR.png\" alt=\"AVG\/GDPR\" class=\"uag-image-2993 lazyload\" width=\"500\" height=\"500\" title=\"AVGGDPR\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d38e66a1\"><h3 class=\"uagb-heading-text\"><strong>GDPR<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">We have had the GDPR available on our platform for years. Also easy to combine again.<\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#AVG-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-39b79d5a\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-aacc1acc wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/03\/LGPD.png ,https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/03\/LGPD.png 780w, https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/03\/LGPD.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/03\/LGPD.png\" alt=\"LGPD\" class=\"uag-image-2978 lazyload\" width=\"500\" height=\"500\" title=\"LGPD\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7cc5d5f5\"><h3 class=\"uagb-heading-text\"><strong>LGPD<\/strong><\/h3><div class=\"uagb-separator\"><\/div><p class=\"uagb-desc-text\">The&nbsp;(LGPD)&nbsp;is the Brazilian data protection law for organizations that process personal data.&nbsp;<\/p><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/het_platform\/#LGPD-portal\">More information<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-71d845b7 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8e4bd462\"><h2 class=\"uagb-heading-text\">We work together with<\/h2><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-01ae2131 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wp-block-uagb-image-gallery uagb-block-b1fc4050\"\n\t\t\t\t\t\tstyle=\"\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery spectra-image-gallery__layout--carousel\">\n\t\t\t\t\t\t\t\t<div class=\"uagb-slick-carousel uagb-block-b1fc4050\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2436'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/logo_full_rgb-ALSO-e1736423297377.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/logo_full_rgb-ALSO-1024x160.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/logo_full_rgb-ALSO-300x47.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/47;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2435'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Arrow-e1736423331391.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Arrow-e1736423331391.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Arrow-300x225.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/225;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2434'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Microsoft-e1736423357105.jpeg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Microsoft-e1736423357105.jpeg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Microsoft-300x300.jpeg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/300;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2439'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/CWSI-e1736423497187.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/CWSI-e1736423497187.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/CWSI-300x71.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/71;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='2449'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/software-one-technologies-partner-logo-e1736424514928.webp\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/software-one-technologies-partner-logo-e1736424514928.webp\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/software-one-technologies-partner-logo-300x120.webp\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/120;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='3321'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/blaud-logo.svg\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/blaud-logo.svg\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/blaud-logo.svg\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class='spectra-image-gallery__media-wrapper' data-spectra-gallery-image-id='3324'>\n\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media spectra-image-gallery__media--carousel\">\n\t\t\t\t<picture>\n\t\t\t\t\t<source media=\"(min-width: 1024px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/InfraHealth_Logo2020_CMYK_OUTLINES_Def-kopie.png\">\n\t\t\t\t\t<source media=\"(min-width: 768px)\" data-srcset=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/InfraHealth_Logo2020_CMYK_OUTLINES_Def-kopie.png\">\n\t\t\t\t\t<img decoding=\"async\" class=\"spectra-image-gallery__media-thumbnail spectra-image-gallery__media-thumbnail--carousel lazyload\" data-src=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/05\/InfraHealth_Logo2020_CMYK_OUTLINES_Def-kopie-300x72.png\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 300px; --smush-placeholder-aspect-ratio: 300\/72;\" \/>\n\t\t\t\t<\/picture>\n\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-blurrer\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"spectra-image-gallery__media-thumbnail-caption-wrapper spectra-image-gallery__media-thumbnail-caption-wrapper--overlay\"><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-05a4a518 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-ade83e03\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-uagb-container uagb-block-b8eca5fa\">\n<div class=\"wp-block-uagb-info-box uagb-block-d84c33b5 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Questions?<\/h2><\/div><\/div><p class=\"uagb-ifb-desc translation-block\">We can imagine that you have questions or are interested in a demo, for example. <br>You can reach us at <strong>+31(0)299 714 505<\/strong> or send us a request via the button below, and we will contact you as soon as possible.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-right is-layout-flex wp-container-core-buttons-is-layout-0752e96d wp-block-buttons-is-layout-flex\" style=\"padding-right:var(--wp--preset--spacing--30);padding-left:var(--wp--preset--spacing--30)\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"\/en\/contact\/\">Contact us<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\"><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bf067554 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-94814167\">\n<div class=\"wp-block-uagb-info-box uagb-block-afb8de21 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><span class=\"uagb-ifb-title-prefix\">About us<\/span><h2 class=\"uagb-ifb-title\">About Cyber Basics<\/h2><\/div><p class=\"uagb-ifb-desc\">Waveland European Lawyers\u2019 smart compliance platform enables thousands of users to apply their policies, procedures and registrations quickly and efficiently. By working with cyber security experts, you get the seamless link between your ISMS policy and the technical measures you need to take to comply with the relevant legislation\/standards.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5d010c34\">\n<div class=\"wp-block-uagb-image uagb-block-c4764945 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"\/wp-content\/uploads\/2025\/02\/Kwadijk1.png ,\/wp-content\/uploads\/2025\/02\/Kwadijk1.png 780w, \/wp-content\/uploads\/2025\/02\/Kwadijk1.png 360w\" data-sizes=\"auto, (max-width: 480px) 150px\" data-src=\"\/wp-content\/uploads\/2025\/02\/Kwadijk1.png\" alt=\"Cybersecurity compliance platform NIS2 ISO27001\" class=\"uag-image-2685 lazyload\" width=\"400\" height=\"285\" title=\"Kwadijk1\" role=\"img\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/285;\" \/><\/figure><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Het slimme compliance platform Voor NIS2 \/ Cyberbeveiligingswet, ISO9001, ISO27001:2022, NEN7510:2024, AVG\/GDPR, LGPD en meer. We hebben het effici\u00ebnt en handig gemaakt Uw cybersecurity compliance platform in \u00e9\u00e9n overzicht 1 modulair SaaS-platform Meerdere ISMS-portalen Werken slim met elkaar samen De portalen NIS2: Cyberbeveiligingswet De Europese NIS2 richtlijn verwerkt in een uitgebreid portaal. NIS2 Directive The [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"class_list":["post-1322","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cybersecurity compliance platform \u2013 Cyber Basics<\/title>\n<meta name=\"description\" content=\"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cyberbasics.org\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cybersecurity compliance platform \u2013 Cyber Basics\" \/>\n<meta property=\"og:description\" content=\"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cyberbasics.org\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Cyber Basics\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T10:22:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/\",\"url\":\"https:\\\/\\\/www.cyberbasics.org\\\/\",\"name\":\"Cybersecurity compliance platform \u2013 Cyber Basics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cyberbasics.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Cyber-Basics-logoblock.webp\",\"datePublished\":\"2025-01-08T15:31:57+00:00\",\"dateModified\":\"2025-10-07T10:22:23+00:00\",\"description\":\"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cyberbasics.org\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cyberbasics.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Cyber-Basics-logoblock.webp\",\"contentUrl\":\"https:\\\/\\\/www.cyberbasics.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Cyber-Basics-logoblock.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cyberbasics.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#website\",\"url\":\"https:\\\/\\\/www.cyberbasics.org\\\/\",\"name\":\"Cyber Basics\",\"description\":\"Start compliance slim en betaalbaar.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#organization\"},\"alternateName\":\"Cyber Basics Compliance platform\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cyberbasics.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#organization\",\"name\":\"Cyber Basics\",\"alternateName\":\"The Compliance Platform\",\"url\":\"https:\\\/\\\/www.cyberbasics.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cyberbasics.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Cyber-Basics-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.cyberbasics.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Cyber-Basics-logo.png\",\"width\":768,\"height\":192,\"caption\":\"Cyber Basics\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cyberbasics.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cyber-basics\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cybersecurity compliance platform \u2013 Cyber Basics","description":"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cyberbasics.org\/en\/","og_locale":"en_GB","og_type":"article","og_title":"Cybersecurity compliance platform \u2013 Cyber Basics","og_description":"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.","og_url":"https:\/\/www.cyberbasics.org\/en\/","og_site_name":"Cyber Basics","article_modified_time":"2025-10-07T10:22:23+00:00","og_image":[{"url":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cyberbasics.org\/","url":"https:\/\/www.cyberbasics.org\/","name":"Cybersecurity compliance platform \u2013 Cyber Basics","isPartOf":{"@id":"https:\/\/www.cyberbasics.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cyberbasics.org\/#primaryimage"},"image":{"@id":"https:\/\/www.cyberbasics.org\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp","datePublished":"2025-01-08T15:31:57+00:00","dateModified":"2025-10-07T10:22:23+00:00","description":"Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving.","breadcrumb":{"@id":"https:\/\/www.cyberbasics.org\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cyberbasics.org\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cyberbasics.org\/#primaryimage","url":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp","contentUrl":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/Cyber-Basics-logoblock.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cyberbasics.org\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cyberbasics.org\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.cyberbasics.org\/#website","url":"https:\/\/www.cyberbasics.org\/","name":"Cyber Basics","description":"Start compliance slim en betaalbaar.","publisher":{"@id":"https:\/\/www.cyberbasics.org\/#organization"},"alternateName":"Cyber Basics Compliance platform","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cyberbasics.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.cyberbasics.org\/#organization","name":"Cyber Basics","alternateName":"The Compliance Platform","url":"https:\/\/www.cyberbasics.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.cyberbasics.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Cyber-Basics-logo.png","contentUrl":"https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/01\/Cyber-Basics-logo.png","width":768,"height":192,"caption":"Cyber Basics"},"image":{"@id":"https:\/\/www.cyberbasics.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/cyber-basics\/"]}]}},"spectra_custom_meta":{"site-sidebar-layout":["no-sidebar"],"site-content-layout":["page-builder"],"site-post-title":["disabled"],"ast-featured-img":["disabled"],"theme-transparent-header-meta":["enabled"],"_yoast_wpseo_estimated-reading-time-minutes":["5"],"_yoast_wpseo_content_score":["90"],"astra-main-page-id":["59763"],"ast_self_id_59763":["1"],"ast-site-content-layout":["full-width-container"],"site-content-style":["unboxed"],"site-sidebar-style":["unboxed"],"astra-migrate-meta-layouts":["set"],"_wxr_import_user_slug":["kalpeshb"],"_astra_sites_imported_post":["1"],"_astra_sites_enable_for_batch":["1"],"_edit_lock":["1759838612:2"],"_elementor_template_type":["wp-page"],"_wp_page_template":["default"],"_edit_last":["2"],"footnotes":[""],"_yoast_wpseo_focuskw":["Cybersecurity compliance platform"],"_yoast_wpseo_metadesc":["Cybersecurity compliance platform voor NIS2, ISO27001, AVG en meer. Cyber Basics helpt organisaties eenvoudig voldoen aan wet- en regelgeving."],"_yoast_wpseo_linkdex":["79"],"_yoast_wpseo_title":["Cybersecurity compliance platform \u2013 Cyber Basics"],"ao_post_optimize":["a:6:{s:16:\"ao_post_optimize\";s:2:\"on\";s:19:\"ao_post_js_optimize\";s:2:\"on\";s:20:\"ao_post_css_optimize\";s:2:\"on\";s:12:\"ao_post_ccss\";s:2:\"on\";s:16:\"ao_post_lazyload\";s:2:\"on\";s:15:\"ao_post_preload\";s:0:\"\";}"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:18;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:28;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:3;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:12;s:18:\"uagb\/image-gallery\";i:1;s:13:\"uagb\/info-box\";i:9;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:206482:\".wp-block-uagb-container.uagb-block-494c42c4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-494c42c4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-494c42c4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-494c42c4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-494c42c4 .uagb-container__video-wrap video{opacity: 0.2;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-494c42c4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-494c42c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: space-between;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-494c42c4{min-height: 584px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 60% 57%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgroundheader.webp);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-494c42c4::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background-image: linear-gradient(137deg,rgb(48,85,163) 0%,rgba(1,1,1,0.92) 100%);opacity: 0.8;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading .uagb-heading-text{color: #ffffff;text-shadow: 0px 0px 10px var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading {padding-top: 140px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-5);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66 .uagb-heading-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9fed0b66 .uagb-desc-text{font-weight: 500;font-size: 21px;}.wp-block-uagb-container.uagb-block-2eac84a9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2eac84a9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2eac84a9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2eac84a9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2eac84a9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eac84a9{max-width: 400px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eac84a9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2eac84a9{min-height: 165px;box-shadow: 0px 4px 12px 0px #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 19px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background: linear-gradient(44deg,rgba(237,237,237,0.9) 0%,rgba(240,240,240,0.93) 100%);;background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-e78c5b8d .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;color: #ffffff;}.uagb-block-e78c5b8d .uagb-ifb-icon svg{fill: #ffffff;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;color: #ffffff;fill: #ffffff;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 24px;font-size: 24px;color: #ffffff;fill: #ffffff;}.uagb-block-e78c5b8d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 24px;height: 24px;line-height: 24px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: #ffffff;fill: #ffffff;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 24px;line-height: 24px;font-size: 24px;color: #ffffff;fill: #ffffff;}.uagb-block-e78c5b8d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-e78c5b8d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-e78c5b8d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-e78c5b8d.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 6px;}.uagb-block-e78c5b8d.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-7);margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-e78c5b8d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-e78c5b8d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-e78c5b8d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-e78c5b8d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 20px;padding-bottom: 0px;padding-left: 20px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 20px;padding-bottom: 0px;padding-left: 20px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e78c5b8d .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-bd487c2d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bd487c2d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bd487c2d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bd487c2d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bd487c2d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd487c2d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd487c2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bd487c2d{min-height: 527px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(180deg,rgba(255,255,255,0.99) 0%,rgba(230,230,230,0.5) 100%);;background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading {text-align: center;padding-top: 30px;padding-right: 0px;padding-bottom: 20px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb .uagb-heading-text{font-size: 40px;letter-spacing: -2px;}.uagb-block-006c6494 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-006c6494 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-006c6494 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-006c6494 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-006c6494 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-006c6494 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-006c6494.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-006c6494.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-006c6494 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-006c6494 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-006c6494 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-006c6494 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-006c6494 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-006c6494.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-006c6494.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-006c6494 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-006c6494.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9a95a3a8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-9a95a3a8 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-9a95a3a8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-9a95a3a8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9a95a3a8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9a95a3a8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9a95a3a8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-9a95a3a8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-9a95a3a8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9a95a3a8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9a95a3a8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9a95a3a8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a95a3a8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-9a95a3a8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a95a3a8 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0358dc83 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-0358dc83 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-0358dc83 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-0358dc83 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-0358dc83 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-0358dc83 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-0358dc83.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-0358dc83.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-0358dc83 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-0358dc83 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-0358dc83 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-0358dc83 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0358dc83 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-0358dc83.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-0358dc83.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0358dc83 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ee927032 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-ee927032 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-ee927032 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-ee927032 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-ee927032 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-ee927032 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ee927032.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-ee927032.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-ee927032 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ee927032 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ee927032 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ee927032 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ee927032 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-ee927032.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ee927032.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ee927032 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-ee927032.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3b71a969 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-3b71a969 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-3b71a969 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-3b71a969 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3b71a969 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3b71a969 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3b71a969.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-3b71a969.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-3b71a969 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3b71a969 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3b71a969 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3b71a969 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b71a969 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-3b71a969.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-3b71a969.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b71a969 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-25814703 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #3055a3;}.uagb-block-25814703 .uagb-ifb-icon svg{fill: #3055a3;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-25814703 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #3055a3;fill: #3055a3;}.uagb-block-25814703 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25814703 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25814703 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-25814703.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-25814703.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-25814703 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-25814703 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-25814703 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-25814703 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25814703 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-25814703.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-25814703.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{margin-top: 10px;margin-right: 10px;margin-bottom: 0px;margin-left: 10px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25814703 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap{text-align: center;}[dir=rtl] .uagb-block-25814703.uagb-infobox-icon-above-title{text-align: center;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading {text-align: center;padding-top: 10px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e .uagb-heading-text{font-size: 40px;letter-spacing: -2px;}.wp-block-uagb-container.uagb-block-587003d3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-587003d3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-587003d3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-587003d3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-587003d3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-587003d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-587003d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-587003d3{min-height: 170px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #000000;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-de867c4d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-de867c4d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-de867c4d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-de867c4d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-de867c4d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de867c4d{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de867c4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-de867c4d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-447ba5b4.wp-block-uagb-counter{text-align: center;margin-top: 18px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{fill: #4B4F58;width: 30px;height: 30px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__title{font-style: normal;color: #dcdcdc;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number{font-style: normal;color: #fafafa;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-447ba5b4.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{max-width: 230px;}.uagb-block-447ba5b4.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg circle{stroke-width: 8px;stroke: #eaeaea;r: 111px;cx: 115px;cy: 115px;}.uagb-block-447ba5b4.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg .uagb-counter-circle__progress{stroke: #007cba;stroke-dasharray: 697.43px;stroke-dashoffset: 697.43px;}.uagb-block-447ba5b4.wp-block-uagb-counter--bars{flex-direction: column;}.uagb-block-447ba5b4.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{background: #eaeaea;}.uagb-block-447ba5b4.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{background: #007cba;}.wp-block-uagb-container.uagb-block-a95a4438 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a95a4438 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a95a4438 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a95a4438 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a95a4438 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a95a4438{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a95a4438 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-a95a4438{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-57a687ba.wp-block-uagb-counter{text-align: center;margin-top: 18px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{fill: #4B4F58;width: 30px;height: 30px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__title{font-style: normal;color: #dcdcdc;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number{font-style: normal;color: #fafafa;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-57a687ba.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{max-width: 230px;}.uagb-block-57a687ba.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg circle{stroke-width: 8px;stroke: #eaeaea;r: 111px;cx: 115px;cy: 115px;}.uagb-block-57a687ba.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg .uagb-counter-circle__progress{stroke: #007cba;stroke-dasharray: 697.43px;stroke-dashoffset: 697.43px;}.uagb-block-57a687ba.wp-block-uagb-counter--bars{flex-direction: column;}.uagb-block-57a687ba.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{background: #eaeaea;}.uagb-block-57a687ba.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{background: #007cba;}.wp-block-uagb-container.uagb-block-7f2408d3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7f2408d3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7f2408d3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7f2408d3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7f2408d3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f2408d3{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f2408d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-7f2408d3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-595d0164.wp-block-uagb-counter{text-align: center;margin-top: 18px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{fill: #4B4F58;width: 30px;height: 30px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__title{font-style: normal;color: #dcdcdc;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number{font-style: normal;color: #fafafa;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.uagb-block-595d0164.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container{max-width: 170px;}.uagb-block-595d0164.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg circle{stroke-width: 8px;stroke: #eaeaea;r: 81px;cx: 85px;cy: 85px;}.uagb-block-595d0164.wp-block-uagb-counter--circle .wp-block-uagb-counter-circle-container svg .uagb-counter-circle__progress{stroke: #007cba;stroke-dasharray: 508.94px;stroke-dashoffset: 508.94px;}.uagb-block-595d0164.wp-block-uagb-counter--bars{flex-direction: column;}.uagb-block-595d0164.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container{background: #eaeaea;}.uagb-block-595d0164.wp-block-uagb-counter--bars .wp-block-uagb-counter-bars-container .wp-block-uagb-counter__number{background: #007cba;}.wp-block-uagb-container.uagb-block-3cd30340 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3cd30340 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3cd30340 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3cd30340 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3cd30340 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3cd30340{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3cd30340 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-3cd30340{min-height: 361px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #3055a3;;row-gap: 20px;column-gap: 20px;}.uagb-block-1ddfafc8.wp-block-uagb-image{margin-top: 13px;margin-right: 13px;margin-bottom: 13px;margin-left: 13px;text-align: center;justify-content: center;align-self: center;}.uagb-block-1ddfafc8 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 400px;height: 400px;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1ddfafc8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);text-shadow: 0px 0px 5px var(--ast-global-color-7);}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading {text-align: center;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1e9040bf.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);text-shadow: 0px 0px 5px var(--ast-global-color-7);}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading {text-align: center;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-4bf80251.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);text-shadow: 0px 0px 5px var(--ast-global-color-7);}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading {text-align: center;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5262aa25.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-5fcee4f8 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fcee4f8 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fcee4f8 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5fcee4f8 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5fcee4f8 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fcee4f8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fcee4f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5fcee4f8{box-shadow: 0px 0px   #00000070 ;padding-top: 50px;padding-bottom: 70px;padding-left: 40px;padding-right: 40px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background: linear-gradient(139deg,rgba(255,255,255,0.5) 0%,rgba(255,255,255,0.51) 33%,rgba(5,30,74,0.41) 100%);;background-clip: padding-box;row-gap: 0px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149 .uagb-heading-text{font-size: 40px;letter-spacing: -2px;}.wp-block-uagb-container.uagb-block-4a8e1942 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a8e1942 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a8e1942 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a8e1942 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a8e1942 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8e1942{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8e1942 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a8e1942{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0ad6ff4e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0ad6ff4e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0ad6ff4e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0ad6ff4e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0ad6ff4e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ad6ff4e{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ad6ff4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0ad6ff4e{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-930d8e85.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-930d8e85 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-930d8e85.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-930d8e85.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: auto;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3974de5a .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-86432e93 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-86432e93 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-86432e93 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-86432e93 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-86432e93 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-86432e93{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-86432e93 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-86432e93{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-fb56e858.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-fb56e858 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-fb56e858.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-fb56e858.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: auto;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-f1094065.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f1094065.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f1094065.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f1094065.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f1094065.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f1094065 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-01df3a06 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01df3a06 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01df3a06 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01df3a06 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01df3a06 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01df3a06{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01df3a06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-01df3a06{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-a2ec8e61.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-a2ec8e61 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a2ec8e61.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b17f6847 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-c988f562 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c988f562 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c988f562 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c988f562 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c988f562 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c988f562{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c988f562 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c988f562{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-a35d235b.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-a35d235b .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-a35d235b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-a35d235b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b07219d5 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-efea18e5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-efea18e5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-efea18e5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-efea18e5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-efea18e5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efea18e5{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efea18e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-efea18e5{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-8a765627.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-8a765627 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-8a765627.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8a765627.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-70c2c644 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-2fc1764d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2fc1764d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2fc1764d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2fc1764d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2fc1764d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2fc1764d{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2fc1764d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-2fc1764d{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-daca879b.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-daca879b .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-daca879b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-daca879b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86672fbf .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-a890f82a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a890f82a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a890f82a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a890f82a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a890f82a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a890f82a{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a890f82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a890f82a{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-c175cf2f.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-c175cf2f .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c175cf2f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-79357460.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-79357460.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-79357460.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-79357460.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-79357460.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-79357460 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-48a31e6a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48a31e6a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48a31e6a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-48a31e6a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-48a31e6a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a31e6a{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a31e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-48a31e6a{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-2675d6b0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-2675d6b0 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-2675d6b0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8f982c10 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-9d8fb7eb .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d8fb7eb .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d8fb7eb .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9d8fb7eb .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9d8fb7eb .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d8fb7eb{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d8fb7eb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9d8fb7eb{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-c3cf6ea0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-c3cf6ea0 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c3cf6ea0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d38e66a1 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-39b79d5a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-39b79d5a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-39b79d5a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-39b79d5a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-39b79d5a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39b79d5a{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39b79d5a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-39b79d5a{box-shadow: 0px 0px   #00000070 ;padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 0px;}.uagb-block-aacc1acc.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-aacc1acc .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 2px 5px -1px #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-aacc1acc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 500px;height: px;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5.wp-block-uagb-advanced-heading .uagb-separator{border-top-style: solid;border-top-width: 2px;width: 12%;border-color: #0170b9;margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7cc5d5f5 .uagb-heading-text{margin-bottom: 10px;}.wp-block-uagb-container.uagb-block-71d845b7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71d845b7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71d845b7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71d845b7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71d845b7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71d845b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71d845b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-71d845b7{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #ffffff;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-8e4bd462.wp-block-uagb-advanced-heading {text-align: center;padding-top: 50px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-8e4bd462.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8e4bd462.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8e4bd462.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8e4bd462.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-01ae2131 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01ae2131 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01ae2131 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01ae2131 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01ae2131 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01ae2131{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01ae2131 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-01ae2131{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #ffffff;;row-gap: 20px;column-gap: 20px;}.uagb-block-b1fc4050.wp-block-uagb-image-gallery{padding: 0px 0px 20px 0px;visibility: hidden;}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows svg{fill: var(--ast-global-color-0);}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows--carousel{border-top-left-radius: 50px;border-top-right-radius: 50px;border-bottom-left-radius: 50px;border-bottom-right-radius: 50px;border-style: none;}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows--carousel.slick-prev{left: -47px;}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows--carousel.slick-next{right: -47px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel ul.slick-dots{top: 8px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel ul.slick-dots li button:before{color: var(--ast-global-color-0);}.uagb-block-b1fc4050 .spectra-image-gallery__control-dots li button::before{color: var(--ast-global-color-0);}.uagb-block-b1fc4050 .spectra-image-gallery__control-loader{margin-top: 8px;}.uagb-block-b1fc4050 .spectra-image-gallery__control-loader div{background-color: var(--ast-global-color-0);width: 18px;height: 18px;border-radius: 100%;padding: 0;}.uagb-block-b1fc4050 .spectra-image-gallery__control-button{margin-top: 8px;padding:    ;background-color: var(--ast-global-color-0);font-style: normal;text-decoration: none;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--grid{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel{margin-bottom: 8px !important;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--tiled{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media{box-shadow: 0px 0px   ;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-blurrer{-webkit-backdrop-filter: none;backdrop-filter: none;box-shadow: 0 0 transparent;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption-wrapper--overlay{background-color: rgba(0,0,0,0);}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption-wrapper--bar-inside{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption a{color: rgba(0,0,0,0);}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption{color: rgba(0,0,0,0);text-align: center;font-style: normal;text-decoration: none;padding: 8px 8px 8px 8px;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption--overlay{-webkit-align-items: center;align-items: center;-webkit-justify-content: center;justify-content: center;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0);border-color: rgba(0,0,0,0);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-b1fc4050spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-inside{background-color: rgba(0,0,0,0.75);}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption--bar-outside{background-color: rgba(0,0,0,0.75);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption{color: rgba(255,255,255,1);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail-caption a{color: rgba(255,255,255,1);}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox{background-color: rgba(0,0,0,0.75);backdrop-filter: blur( 5px);}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--caption{color: rgba(255,255,255,1);background: linear-gradient(rgba(0,0,0,0), rgba(0,0,0,1));min-height: 50px;font-style: normal;text-decoration: none;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--thumbnails-wrapper{background-color: transparent;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--count{top: 10px;left: 10px;color: rgba(255,255,255,1);font-weight: normal;font-size: calc(24px * 3 \/ 4 );line-height: calc(24px * 3 \/ 4 );}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close{top: 10px;right: 10px;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--close svg{width: 24px;height: 24px;fill: rgba(255,255,255,1);}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev{left: 10px;color: rgba(255,255,255,1);}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next{right: 10px;color: rgba(255,255,255,1);}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{right: 10px;left: auto;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{left: 10px;right: auto;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:hover .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-b1fc4050 .spectra-image-gallery__media-wrapper:focus-visible .spectra-image-gallery__media-thumbnail{-webkit-filter: none;filter: none;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .slick-dots{margin-bottom: 30px !important;}.wp-block-uagb-container.uagb-block-05a4a518 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-05a4a518 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-05a4a518 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-05a4a518 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-05a4a518 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05a4a518{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05a4a518 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-05a4a518{min-height: 410px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 51% 69%;background-size: cover;background-attachment: fixed;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgrfooter-e1736407403675.webp);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ade83e03 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ade83e03 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ade83e03 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ade83e03 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ade83e03 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ade83e03{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ade83e03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-ade83e03{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b8eca5fa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b8eca5fa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b8eca5fa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b8eca5fa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b8eca5fa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b8eca5fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b8eca5fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b8eca5fa{min-height: 265px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background: linear-gradient(90deg,rgba(255,255,255,0.96) 0%,rgba(217,217,217,0.94) 100%);;background-clip: padding-box;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-d84c33b5 .uagb-ifb-icon{width: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-ifb-icon > span{font-size: 50px;width: 50px;line-height: 50px;color: #333;}.uagb-block-d84c33b5 .uagb-ifb-icon svg{fill: #333;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 50px;height: 50px;line-height: 50px;font-size: 50px;color: #333;fill: #333;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 50px;font-size: 50px;color: #333;fill: #333;}.uagb-block-d84c33b5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 50px;height: 50px;line-height: 50px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 50px;line-height: 50px;font-size: 50px;color: #333;fill: #333;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 50px;line-height: 50px;font-size: 50px;color: #333;fill: #333;}.uagb-block-d84c33b5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-d84c33b5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-d84c33b5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d84c33b5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-d84c33b5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 10px;}.uagb-block-d84c33b5 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d84c33b5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d84c33b5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d84c33b5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d84c33b5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 20px;padding-bottom: 0px;padding-left: 20px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 20px;padding-bottom: 0px;padding-left: 20px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d84c33b5 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox-left{text-align: right;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox-right{text-align: left;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-bf067554 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf067554 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf067554 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bf067554 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bf067554 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf067554{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf067554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-bf067554{min-height: 400px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 26% 30%;background-size: cover;background-attachment: scroll;background-image: url(\/wp-content\/uploads\/2025\/01\/background.png);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-94814167 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-94814167 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-94814167 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-94814167 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-94814167 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94814167{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94814167 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-94814167{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-afb8de21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-afb8de21 .uagb-ifb-icon svg{fill: #333;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-afb8de21 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-afb8de21 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-afb8de21 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-afb8de21 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-afb8de21.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 10px;}.uagb-block-afb8de21.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-afb8de21 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-afb8de21 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-afb8de21 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-afb8de21 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-afb8de21 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-afb8de21.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-afb8de21.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 25px;padding-bottom: 0px;padding-left: 25px;}.uagb-block-afb8de21.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 25px;padding-bottom: 0px;padding-left: 25px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-afb8de21 .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-5d010c34 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5d010c34 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5d010c34 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5d010c34 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5d010c34 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d010c34{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d010c34 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5d010c34{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-c4764945.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-c4764945.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-c4764945.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-494c42c4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-494c42c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-494c42c4{min-height: 480px;padding-top: 70px;padding-bottom: 10px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgroundheader.webp);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-494c42c4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background-image: linear-gradient(137deg,rgb(48,85,163) 0%,rgba(1,1,1,0.92) 100%);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eac84a9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eac84a9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-2eac84a9{padding-top: 10px;padding-bottom: 10px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 19px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(44deg,rgba(237,237,237,0.9) 0%,rgba(240,240,240,0.93) 100%);;background-clip: padding-box;align-items: center;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e78c5b8d .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd487c2d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd487c2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bd487c2d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(180deg,rgba(255,255,255,0.99) 0%,rgba(230,230,230,0.5) 100%);;background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-006c6494 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a95a3a8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0358dc83 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ee927032 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b71a969 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25814703 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-587003d3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-587003d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-587003d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #000000;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de867c4d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de867c4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-de867c4d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a95a4438{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a95a4438 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a95a4438{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f2408d3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f2408d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7f2408d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3cd30340{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3cd30340 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3cd30340{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #3055a3;;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 400px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fcee4f8{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fcee4f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5fcee4f8{padding-top: 80px;padding-bottom: 50px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(139deg,rgba(255,255,255,0.5) 0%,rgba(255,255,255,0.51) 33%,rgba(5,30,74,0.41) 100%);;background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading {text-align: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8e1942{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8e1942 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4a8e1942{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ad6ff4e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ad6ff4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0ad6ff4e{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-86432e93{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-86432e93 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-86432e93{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01df3a06{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01df3a06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-01df3a06{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c988f562{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c988f562 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c988f562{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efea18e5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efea18e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-efea18e5{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2fc1764d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2fc1764d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2fc1764d{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a890f82a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a890f82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a890f82a{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a31e6a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a31e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-48a31e6a{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d8fb7eb{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d8fb7eb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9d8fb7eb{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39b79d5a{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39b79d5a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-39b79d5a{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71d845b7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71d845b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-71d845b7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01ae2131{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01ae2131 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-01ae2131{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.uagb-block-b1fc4050.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-b1fc4050 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--grid{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--tiled{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05a4a518{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05a4a518 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-05a4a518{padding-top: 50px;padding-bottom: 50px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgrfooter-e1736407403675.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ade83e03{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ade83e03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-ade83e03{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b8eca5fa{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b8eca5fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b8eca5fa{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(90deg,rgba(255,255,255,0.96) 0%,rgba(217,217,217,0.94) 100%);;background-clip: padding-box;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 50px;height: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d84c33b5 .uagb-ifb-icon{width: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-ifb-icon > span{font-size: 50px;width: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-iconbox-icon-wrap{width: 50px;height: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf067554{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf067554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-bf067554{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(\/wp-content\/uploads\/2025\/01\/background.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94814167{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94814167 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-94814167{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-afb8de21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d010c34{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d010c34 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5d010c34{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-494c42c4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-494c42c4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;justify-content: flex-end;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-494c42c4{min-height: 414px;padding-top: 0px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgroundheader.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-block-494c42c4::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);background-image: linear-gradient(137deg,rgb(48,85,163) 0%,rgba(1,1,1,0.92) 100%);opacity: 0.8;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eac84a9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eac84a9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2eac84a9{padding-top: 10px;padding-bottom: 10px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 19px !important;margin-left: 0px;margin-right: 0px;order: initial;background: linear-gradient(44deg,rgba(237,237,237,0.9) 0%,rgba(240,240,240,0.93) 100%);;background-clip: padding-box;align-items: center;flex-wrap: wrap;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 24px;height: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 24px;line-height: 24px;font-size: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-e78c5b8d .uagb-ifb-icon{width: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-ifb-icon > span{font-size: 24px;width: 24px;line-height: 24px;}.uagb-block-e78c5b8d .uagb-iconbox-icon-wrap{width: 24px;height: 24px;line-height: 24px;}.uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-e78c5b8d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bd487c2d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bd487c2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bd487c2d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(180deg,rgba(255,255,255,0.99) 0%,rgba(230,230,230,0.5) 100%);;background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-61309fdb.wp-block-uagb-advanced-heading {text-align: center;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-006c6494 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-006c6494 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-006c6494.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9a95a3a8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9a95a3a8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-9a95a3a8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-0358dc83 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-0358dc83 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-0358dc83.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ee927032 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-ee927032 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-ee927032.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3b71a969 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3b71a969 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-3b71a969.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25814703 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25814703 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-25814703.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-71c3852e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-587003d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-587003d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-587003d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #000000;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-de867c4d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-de867c4d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-de867c4d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-447ba5b4.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a95a4438{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a95a4438 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a95a4438{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-57a687ba.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f2408d3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f2408d3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7f2408d3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__icon svg{width: 30px;height: 30px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-prefix{margin-right: 0px;}.uagb-block-595d0164.wp-block-uagb-counter .wp-block-uagb-counter__number .uagb-counter-block-suffix{margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3cd30340{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3cd30340 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3cd30340{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #3055a3;;}.uagb-block-1ddfafc8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 400px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5fcee4f8{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5fcee4f8 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-5fcee4f8{padding-top: 50px;padding-bottom: 50px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(139deg,rgba(255,255,255,0.5) 0%,rgba(255,255,255,0.51) 33%,rgba(5,30,74,0.41) 100%);;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-5fcee4f8.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-5fcee4f8.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-2b5f3149.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8e1942{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8e1942 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 70px;}.wp-block-uagb-container.uagb-block-4a8e1942{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 70px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ad6ff4e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ad6ff4e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0ad6ff4e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-930d8e85.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-86432e93{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-86432e93 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-86432e93{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-fb56e858.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01df3a06{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01df3a06 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-01df3a06{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-a2ec8e61.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c988f562{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c988f562 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c988f562{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-a35d235b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efea18e5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efea18e5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-efea18e5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-8a765627.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2fc1764d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2fc1764d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2fc1764d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-daca879b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a890f82a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a890f82a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a890f82a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-c175cf2f.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-48a31e6a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-48a31e6a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-48a31e6a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-2675d6b0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9d8fb7eb{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9d8fb7eb > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9d8fb7eb{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-c3cf6ea0.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-39b79d5a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-39b79d5a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-39b79d5a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-aacc1acc.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 500px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71d845b7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71d845b7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-71d845b7{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01ae2131{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01ae2131 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-01ae2131{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ffffff;;}.uagb-block-b1fc4050.wp-block-uagb-image-gallery{padding:    ;}.uagb-block-b1fc4050 .spectra-image-gallery__control-arrows--carousel{border-style: none;}.uagb-block-b1fc4050 .spectra-image-gallery__control-button{padding:    ;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--grid{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--isogrid .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry{margin: -50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--masonry .spectra-image-gallery__media-wrapper--isotope{padding: 50px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .spectra-image-gallery__media-wrapper{padding: 0px 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--carousel .slick-list{margin: 0px -100px;}.uagb-block-b1fc4050 .spectra-image-gallery__layout--tiled .spectra-image-gallery__media-wrapper{grid-gap: 100px;}.uagb-block-b1fc4050 .spectra-image-gallery__media-thumbnail-caption{padding: 8px 8px 8px 8px;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-prev{left: auto;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main.swiper-rtl .swiper-button-next{right: auto;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-prev::after{font-size: 24px;}.uagb-block-b1fc4050+.spectra-image-gallery__control-lightbox .spectra-image-gallery__control-lightbox--main .swiper-button-next::after{font-size: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-05a4a518{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-05a4a518 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-05a4a518{min-height: 394px;padding-top: 50px;padding-bottom: 50px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-position: 52% 27%;background-image: url(https:\/\/www.cyberbasics.org\/wp-content\/uploads\/2025\/04\/backgrfooter-e1736407403675.webp);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ade83e03{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ade83e03 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-ade83e03{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b8eca5fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b8eca5fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b8eca5fa{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background: linear-gradient(90deg,rgba(255,255,255,0.96) 0%,rgba(217,217,217,0.94) 100%);;background-clip: padding-box;flex-wrap: wrap;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 50px;height: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 50px;line-height: 50px;font-size: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d84c33b5 .uagb-ifb-icon{width: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-ifb-icon > span{font-size: 50px;width: 50px;line-height: 50px;}.uagb-block-d84c33b5 .uagb-iconbox-icon-wrap{width: 50px;height: 50px;line-height: 50px;}.uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-d84c33b5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bf067554{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bf067554 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-bf067554{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-image: url(\/wp-content\/uploads\/2025\/01\/background.png);background-clip: padding-box;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-94814167{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-94814167 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-94814167{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-afb8de21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-afb8de21 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}[dir=rtl] .uagb-block-afb8de21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5d010c34{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5d010c34 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5d010c34{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-c4764945.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-container.uagb-block-37e0289e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37e0289e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37e0289e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-37e0289e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-37e0289e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-37e0289e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37e0289e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1140px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-37e0289e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37e0289e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37e0289e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-37e0289e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-37e0289e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-37e0289e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-37e0289e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}}\";s:2:\"js\";s:4887:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBCounter.init( '.uagb-block-447ba5b4', {\"layout\":\"number\",\"heading\":\"Cyber Basics gebruikers\",\"numberPrefix\":\"\",\"numberSuffix\":\"+\",\"startNumber\":0,\"endNumber\":1000,\"totalNumber\":1000,\"decimalPlaces\":0,\"animationDuration\":1500,\"thousandSeparator\":\".\",\"circleSize\":230,\"circleStokeSize\":8,\"isFrontend\":true} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBCounter.init( '.uagb-block-57a687ba', {\"layout\":\"number\",\"heading\":\"Verschillende portalen\",\"numberPrefix\":\"\",\"numberSuffix\":\"\",\"startNumber\":0,\"endNumber\":15,\"totalNumber\":100,\"decimalPlaces\":0,\"animationDuration\":1500,\"thousandSeparator\":\",\",\"circleSize\":230,\"circleStokeSize\":8,\"isFrontend\":true} );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBCounter.init( '.uagb-block-595d0164', {\"layout\":\"number\",\"heading\":\"Stappen naar compliance\",\"numberPrefix\":\"in \",\"numberSuffix\":\"\",\"startNumber\":0,\"endNumber\":3,\"totalNumber\":100,\"decimalPlaces\":0,\"animationDuration\":1500,\"thousandSeparator\":\",\",\"circleSize\":170,\"circleStokeSize\":8,\"isFrontend\":true} );\n});\njQuery(document).ready(function () {\n\t\t\t\tlet scope = jQuery(\".wp-block-uagb-image-gallery.uagb-block-b1fc4050\");\n\t\t\t\tif ( scope.length ) { \n\t\t\t\t\tscope.css(\"visibility\", \"visible\");\n\t\t\t\t\tlet getSlickCarousel = scope.find(\".uagb-slick-carousel\");\n\t\t\t\t\tif( getSlickCarousel.length ) {\n\t\t\t\t\t\tgetSlickCarousel.slick({\"arrows\":true,\"dots\":true,\"initialSlide\":2,\"infinite\":true,\"autoplay\":true,\"autoplaySpeed\":2000,\"pauseOnHover\":true,\"speed\":500,\"slidesToShow\":3,\"prevArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-prev slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='43' height='43'><path d='M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z'><\/path><\/svg><\/button>\",\"nextArrow\":\"<button type='button' data-role='none' class='spectra-image-gallery__control-arrows spectra-image-gallery__control-arrows--carousel slick-next slick-arrow' aria-label='Previous' tabindex='0' role='button'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 256 512' width='43' height='43'><path d='M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z'><\/path><\/svg><\/button>\",\"rtl\":false,\"responsive\":[{\"breakpoint\":1024,\"settings\":{\"slidesToShow\":3}},{\"breakpoint\":767,\"settings\":{\"slidesToShow\":2}}]});\n\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t});\t\t\twindow.addEventListener( 'DOMContentLoaded', () => {\n\t\t\t\tconst blockScope = document.querySelector( '.uagb-block-b1fc4050' );\n\t\t\t\tif ( ! blockScope ) {\n\t\t\t\t\treturn;\n\t\t\t\t}\n\n\t\t\t\tconst regexCustomURL = new RegExp( '^((http|https):[\/]{2})(www.)?((?!www)[a-zA-Z0-9@:%._\\+~#?&\/\/=\\-]{2,256})\\.[a-zA-Z]{2,256}\\b([-a-zA-Z0-9@:%._\\+~#?&\/\/=]*)$');\n\t\t\t\tconst customLinks = {\"2434\":\"https:\/\/www.microsoft.com\",\"2435\":\"https:\/\/www.arrow.com\/globalecs\/nl\/\",\"2436\":\"https:\/\/www.also.com\/ec\/cms5\/nl_2400\/2400\/\",\"2439\":\"https:\/\/cwsisecurity.com\/\",\"2449\":\"https:\/\/www.softwareone.com\/nl-nl\",\"3321\":\"https:\/\/blaud.com\/\",\"3324\":\"https:\/\/www.infrahealth.nl\/\"};\n\t\t\t\tconst customLinksBehaviour = {};\n\n\t\t\t\tconst getCustomURL = ( image ) => {\n\t\t\t\t\tconst imageID = parseInt( image.getAttribute( 'data-spectra-gallery-image-id' ) );\n\t\t\t\t\treturn ( regexCustomURL.test( customLinks[ imageID ] ) ? customLinks[ imageID ] : undefined );\n\t\t\t\t}\n\n\t\t\t\tconst openCustomURL = ( customURL, shouldOpenInNewTab ) => {\n\t\t\t\t\tif ( shouldOpenInNewTab ) { \n\t\t\t\t\t\twindow.open(customURL, \"_blank\");\n\t\t\t\t\t} else {\n\t\t\t\t\t\twindow.location.assign( customURL );\n\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\tconst getCustomLinkBehaviour = (caption) => {\n\t\t\t\t\tif (!customLinksBehaviour) {\n\t\t\t\t\t\treturn true;\n\t\t\t\t\t}\n\t\t\t\t\tconst imageId = parseInt(caption.getAttribute('data-spectra-gallery-image-id'));\n\t\t\t\t\treturn !customLinksBehaviour[imageId] === true;\n\t\t\t\t};\n\n\t\t\t\tconst images = blockScope.querySelectorAll( '.spectra-image-gallery__media-wrapper' );\n\t\t\t\tfor ( let i = 0; i < images.length; i++ ) {\n\t\t\t\t\tconst customURL = getCustomURL( images[ i ] );\n\t\t\t\t\tconst shouldOpenInNewTab = getCustomLinkBehaviour( images[ i ] );\n\t\t\t\t\tif ( customURL ) {\n\t\t\t\t\t\timages[ i ].style.cursor = 'pointer';\n\t\t\t\t\t\timages[ i ].addEventListener( 'click', () => openCustomURL( customURL, shouldOpenInNewTab) );\n\n\t\t\t\t\t\t\/\/ Add event listener for Enter and Space key presses\n\t\t\t\t\t\timages[ i ].addEventListener('keydown', (event) => {\n\t\t\t\t\t\tif ( 13 === event.keyCode || 32 === event.keyCode ) {\n\t\t\t\t\t\t\topenCustomURL(customURL, shouldOpenInNewTab);\n\t\t\t\t\t\t}\n\t\t\t\t\t});\n\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t} );\n\t\t });\";s:18:\"current_block_list\";a:18:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:12:\"core\/columns\";i:3;s:11:\"core\/column\";i:6;s:13:\"uagb\/info-box\";i:7;s:12:\"core\/buttons\";i:8;s:11:\"core\/button\";i:11;s:12:\"uagb\/counter\";i:15;s:10:\"uagb\/image\";i:17;s:18:\"uagb\/image-gallery\";i:18;s:11:\"core\/search\";i:19;s:10:\"core\/group\";i:20;s:12:\"core\/heading\";i:21;s:17:\"core\/latest-posts\";i:22;s:20:\"core\/latest-comments\";i:23;s:13:\"core\/archives\";i:24;s:15:\"core\/categories\";i:25;s:10:\"core\/image\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1784099297\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"cbadmin","author_link":"https:\/\/www.cyberbasics.org\/en\/author\/cbadmin\/"},"uagb_comment_info":0,"uagb_excerpt":"Het slimme compliance platform Voor NIS2 \/ Cyberbeveiligingswet, ISO9001, ISO27001:2022, NEN7510:2024, AVG\/GDPR, LGPD en meer. We hebben het effici\u00ebnt en handig gemaakt Uw cybersecurity compliance platform in \u00e9\u00e9n overzicht 1 modulair SaaS-platform Meerdere ISMS-portalen Werken slim met elkaar samen De portalen NIS2: Cyberbeveiligingswet De Europese NIS2 richtlijn verwerkt in een uitgebreid portaal. NIS2 Directive The&hellip;","_links":{"self":[{"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/pages\/1322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/comments?post=1322"}],"version-history":[{"count":278,"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/pages\/1322\/revisions"}],"predecessor-version":[{"id":3762,"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/pages\/1322\/revisions\/3762"}],"wp:attachment":[{"href":"https:\/\/www.cyberbasics.org\/en\/wp-json\/wp\/v2\/media?parent=1322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}